{"id":2798,"date":"2025-12-26T13:57:01","date_gmt":"2025-12-26T13:57:01","guid":{"rendered":"https:\/\/kasperschormans.com\/?post_type=tribe_events&#038;p=2798"},"modified":"2025-12-26T14:06:28","modified_gmt":"2025-12-26T14:06:28","slug":"f4-round-3-spanish-winterseries-motorland","status":"publish","type":"tribe_events","link":"https:\/\/kasperschormans.com\/en\/event\/f4-round-3-spanish-winterseries-motorland\/","title":{"rendered":"F4 Round 3, Spanish Winterseries Motorland \ud83c\uddea\ud83c\uddf8"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-2798","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/tribe_events\/2798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/comments?post=2798"}],"version-history":[{"count":2,"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/tribe_events\/2798\/revisions"}],"predecessor-version":[{"id":2810,"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/tribe_events\/2798\/revisions\/2810"}],"wp:attachment":[{"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/media?parent=2798"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/tags?post=2798"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/kasperschormans.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=2798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}